{"id":102113,"date":"2026-01-07T09:17:04","date_gmt":"2026-01-07T08:17:04","guid":{"rendered":"https:\/\/www.mini-art.nl\/product\/deco-ribbon-welliges-design-gold\/"},"modified":"2026-02-02T13:51:14","modified_gmt":"2026-02-02T12:51:14","slug":"deco-ribbon-welliges-design-gold","status":"publish","type":"product","link":"https:\/\/www.mini-art.nl\/de\/product\/deco-ribbon-welliges-design-gold\/","title":{"rendered":"Deco Ribbon \u2013 Welliges Design \u2013 Gold"},"content":{"rendered":"<p data-start=\"135\" data-end=\"857\">Ein geschwungenes kleines Band ist ein gewebtes Band in einer dominanten <strong data-start=\"213\" data-end=\"223\">goldenen<\/strong> Tr\u00e4gerfarbe mit einem welligen, kurvigen Design. Das Material hat auf beiden Seiten einen matten Textilglanz und f\u00fchlt sich weich an, was das Zuschneiden und Formen in der normalen Verarbeitung erleichtert. Das schmale Design <strong data-start=\"459\" data-end=\"474\">von 5 mm x 13 m<\/strong> erm\u00f6glicht eine pr\u00e4zise Anwendung auf Pappe, Papier und Film ohne Verformung der Oberfl\u00e4che. Das Band franst bei normaler Nutzung nicht und kann mit Kordeln, Gummibanden oder Metallklammern kombiniert werden. Die Lieferung auf einer Rolle erm\u00f6glicht ein kontrolliertes Abwickeln in administrativen und manuellen Verpackungsprozessen. Die Lagerung von Lagern wird in trockenen Gesch\u00e4ftsgebieten empfohlen.     <\/p>\n<p data-start=\"859\" data-end=\"889\"><strong data-start=\"859\" data-end=\"887\">M\u00f6gliche Anwendungen<\/strong><\/p>\n<ul data-start=\"890\" data-end=\"1159\">\n<li data-start=\"890\" data-end=\"946\">\n<p data-start=\"892\" data-end=\"946\">Fertigstellung von Geschenkboxen und Produktpaketen<\/p>\n<\/li>\n<li data-start=\"947\" data-end=\"989\">\n<p data-start=\"949\" data-end=\"989\">Dekoration von Karten und Einladungen<\/p>\n<\/li>\n<li data-start=\"990\" data-end=\"1028\">\n<p data-start=\"992\" data-end=\"1028\">B\u00fcndelung von Brosch\u00fcren und Versandsendungen<\/p>\n<\/li>\n<li data-start=\"1029\" data-end=\"1078\">\n<p data-start=\"1031\" data-end=\"1078\">Verarbeitung in Mehl und Fertigverpackungen<\/p>\n<\/li>\n<li data-start=\"1079\" data-end=\"1122\">\n<p data-start=\"1081\" data-end=\"1122\">Markierung von Gegenst\u00e4nden bei Veranstaltungen<\/p>\n<\/li>\n<li data-start=\"1123\" data-end=\"1159\">\n<p data-start=\"1125\" data-end=\"1159\">Fertigstellung von Ausstellungen und Schaufenstern<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"1161\" data-end=\"1420\"><strong data-start=\"1161\" data-end=\"1189\">Technische Spezifikationen<\/strong><br data-start=\"1189\" data-end=\"1192\">\u2022 Abmessungen: <strong data-start=\"1206\" data-end=\"1221\">5 mm x 13 m<\/strong><br data-start=\"1221\" data-end=\"1224\">\u2022 Material: gewebtes Textil<br data-start=\"1252\" data-end=\"1255\">\u2022 Dominanter Farbtr\u00e4ger: Gold<br data-start=\"1285\" data-end=\"1288\">\u2022 Druck: keine Metallaufschrift oder Symbole sichtbar<br data-start=\"1340\" data-end=\"1343\">\u2022 Produkttyp: <strong data-start=\"1359\" data-end=\"1371\">Rolle Band<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Abmessungen: <strong data-start=\"1206\" data-end=\"1221\">5 mm x 13 m<\/strong><br data-start=\"1221\" data-end=\"1224\">\u2022 Material: gewebtes Textil<br data-start=\"1252\" data-end=\"1255\">\u2022 Dominanter Farbtr\u00e4ger: Gold<br data-start=\"1285\" data-end=\"1288\">\u2022 Druck: keine Metallaufschrift oder Symbole sichtbar<br data-start=\"1340\" data-end=\"1343\">\u2022 Produkttyp: <strong data-start=\"1359\" data-end=\"1371\">Rolle Band<\/strong><\/p>\n","protected":false},"featured_media":97250,"template":"","meta":[],"product_brand":[],"product_cat":[961],"product_tag":[],"class_list":["post-102113","product","type-product","status-publish","has-post-thumbnail","product_cat-farbbandreste","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":{"2":4.5,"4":3.95},"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":null,"_links":{"self":[{"href":"https:\/\/www.mini-art.nl\/de\/wp-json\/wp\/v2\/product\/102113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mini-art.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mini-art.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mini-art.nl\/de\/wp-json\/wp\/v2\/media\/97250"}],"wp:attachment":[{"href":"https:\/\/www.mini-art.nl\/de\/wp-json\/wp\/v2\/media?parent=102113"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mini-art.nl\/de\/wp-json\/wp\/v2\/product_brand?post=102113"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mini-art.nl\/de\/wp-json\/wp\/v2\/product_cat?post=102113"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mini-art.nl\/de\/wp-json\/wp\/v2\/product_tag?post=102113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}